{"id":6331,"date":"2023-12-23T14:50:13","date_gmt":"2023-12-23T13:50:13","guid":{"rendered":"https:\/\/polizeisportverein-heidelberg.de\/?p=6331"},"modified":"2023-12-23T14:50:26","modified_gmt":"2023-12-23T13:50:26","slug":"2023%e5%b9%b4%e3%81%ae%e3%82%af%e3%83%aa%e3%82%b9%e3%83%9e%e3%82%b9","status":"publish","type":"post","link":"https:\/\/polizeisportverein-heidelberg.de\/ja\/2023\/12\/23\/weihnachten-2023\/","title":{"rendered":"\u30af\u30ea\u30b9\u30de\u30b9"},"content":{"rendered":"<p>PSV\u30cf\u30a4\u30c7\u30eb\u30d9\u30eb\u30b0\u3067\u306f\u3001\u4f1a\u54e1\u306e\u7686\u69d8\u3001\u3054\u5bb6\u65cf\u306e\u7686\u69d8\u3001\u305d\u3057\u3066\u5f53\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u3092\u3054\u89a7\u306e\u7686\u69d8\u306b\u3001\u30e1\u30ea\u30fc\u30af\u30ea\u30b9\u30de\u30b9\u3001\u5e73\u7a4f\u306a\u4f11\u65e5\u3001\u305d\u3057\u30662024\u5e74\u306e\u65b0\u5e74\u306e\u3054\u6328\u62f6\u3092\u7533\u3057\u4e0a\u3052\u307e\u3059\u3002<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:12%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif\" alt=\"2023\u5e74\u30af\u30ea\u30b9\u30de\u30b9\" class=\"wp-image-6316\"\/><\/figure>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>PSV\u30cf\u30a4\u30c7\u30eb\u30d9\u30eb\u30b0\u3067\u306f\u3001\u4f1a\u54e1\u306e\u7686\u69d8\u3001\u3054\u5bb6\u65cf\u306e\u7686\u69d8\u3001\u305d\u3057\u3066\u5f53\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u3092\u3054\u89a7\u306e\u7686\u69d8\u306b\u3001\u30e1\u30ea\u30fc\u30af\u30ea\u30b9\u30de\u30b9\u3001\u5e73\u7a4f\u306a\u4f11\u65e5\u3001\u305d\u3057\u30662024\u5e74\u306e\u65b0\u5e74\u306e\u3054\u6328\u62f6\u3092\u7533\u3057\u4e0a\u3052\u307e\u3059\u3002<\/p>","protected":false},"author":25,"featured_media":6316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_psv_pub_social_text":"","_psv_pub_instagram_attachment_id":0,"_psv_pub_social_image_id":0,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"categories":[100],"tags":[],"class_list":["post-6331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-psv-heidelberg"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[14,25],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachten - Polizeisportverein Heidelberg e.V.<\/title>\n<meta name=\"description\" content=\"Allen unseren Mitgliedern, deren Familien und den Besuchern unserer Website w\u00fcnscht der PSV Heidelberg frohe Weihnachten, besinnliche Feiertage und einen guten Rutsch ins Jahr 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polizeisportverein-heidelberg.de\/ja\/2023\/12\/23\/2023\u5e74\u306e\u30af\u30ea\u30b9\u30de\u30b9\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachten - Polizeisportverein Heidelberg e.V.\" \/>\n<meta property=\"og:description\" content=\"Allen unseren Mitgliedern, deren Familien und den Besuchern unserer Website w\u00fcnscht der PSV Heidelberg frohe Weihnachten, besinnliche Feiertage und einen guten Rutsch ins Jahr 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polizeisportverein-heidelberg.de\/ja\/2023\/12\/23\/2023\u5e74\u306e\u30af\u30ea\u30b9\u30de\u30b9\/\" \/>\n<meta property=\"og:site_name\" content=\"Polizeisportverein Heidelberg e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-23T13:50:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-23T13:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/#\\\/schema\\\/person\\\/606d929e0c904d931f9111388b7be25a\"},\"headline\":\"Weihnachten\",\"datePublished\":\"2023-12-23T13:50:13+00:00\",\"dateModified\":\"2023-12-23T13:50:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/\"},\"wordCount\":27,\"image\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/gif-christmas-tree-46-e1703338463885.gif\",\"articleSection\":[\"PSV-Heidelberg\"],\"inLanguage\":\"ja\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/\",\"url\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/\",\"name\":\"Weihnachten - Polizeisportverein Heidelberg e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/gif-christmas-tree-46-e1703338463885.gif\",\"datePublished\":\"2023-12-23T13:50:13+00:00\",\"dateModified\":\"2023-12-23T13:50:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/#\\\/schema\\\/person\\\/606d929e0c904d931f9111388b7be25a\"},\"description\":\"Allen unseren Mitgliedern, deren Familien und den Besuchern unserer Website w\u00fcnscht der PSV Heidelberg frohe Weihnachten, besinnliche Feiertage und einen guten Rutsch ins Jahr 2024.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/gif-christmas-tree-46-e1703338463885.gif\",\"contentUrl\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/gif-christmas-tree-46-e1703338463885.gif\",\"width\":800,\"height\":533,\"caption\":\"Weihnachten 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/2023\\\/12\\\/23\\\/weihnachten-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weihnachten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/#website\",\"url\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/\",\"name\":\"Polizeisportverein Heidelberg e.V.\",\"description\":\"Budo und Ballsport f\u00fcr jedes Alter\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/#\\\/schema\\\/person\\\/606d929e0c904d931f9111388b7be25a\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1c6f2be27b1dead8bc2e492a47d416dcabd8dc824f2ee0bb102949c0ccfef98?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1c6f2be27b1dead8bc2e492a47d416dcabd8dc824f2ee0bb102949c0ccfef98?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1c6f2be27b1dead8bc2e492a47d416dcabd8dc824f2ee0bb102949c0ccfef98?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"sameAs\":[\"https:\\\/\\\/psv-hd.de\"],\"url\":\"https:\\\/\\\/polizeisportverein-heidelberg.de\\\/ja\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u30af\u30ea\u30b9\u30de\u30b9 - Polizeisportverein Heidelberg e.V.","description":"PSV\u30cf\u30a4\u30c7\u30eb\u30d9\u30eb\u30b0\u3067\u306f\u3001\u4f1a\u54e1\u306e\u7686\u69d8\u3001\u3054\u5bb6\u65cf\u306e\u7686\u69d8\u3001\u305d\u3057\u3066\u5f53\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u3092\u3054\u89a7\u306e\u7686\u69d8\u306b\u3001\u30e1\u30ea\u30fc\u30af\u30ea\u30b9\u30de\u30b9\u3001\u5e73\u7a4f\u306a\u4f11\u65e5\u3001\u305d\u3057\u30662024\u5e74\u306e\u65b0\u5e74\u306e\u3054\u6328\u62f6\u3092\u7533\u3057\u4e0a\u3052\u307e\u3059\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polizeisportverein-heidelberg.de\/ja\/2023\/12\/23\/2023\u5e74\u306e\u30af\u30ea\u30b9\u30de\u30b9\/","og_locale":"ja_JP","og_type":"article","og_title":"Weihnachten - Polizeisportverein Heidelberg e.V.","og_description":"Allen unseren Mitgliedern, deren Familien und den Besuchern unserer Website w\u00fcnscht der PSV Heidelberg frohe Weihnachten, besinnliche Feiertage und einen guten Rutsch ins Jahr 2024.","og_url":"https:\/\/polizeisportverein-heidelberg.de\/ja\/2023\/12\/23\/2023\u5e74\u306e\u30af\u30ea\u30b9\u30de\u30b9\/","og_site_name":"Polizeisportverein Heidelberg e.V.","article_published_time":"2023-12-23T13:50:13+00:00","article_modified_time":"2023-12-23T13:50:26+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif","type":"image\/gif"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"Redaktion","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#article","isPartOf":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/"},"author":{"name":"Redaktion","@id":"https:\/\/polizeisportverein-heidelberg.de\/#\/schema\/person\/606d929e0c904d931f9111388b7be25a"},"headline":"Weihnachten","datePublished":"2023-12-23T13:50:13+00:00","dateModified":"2023-12-23T13:50:26+00:00","mainEntityOfPage":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/"},"wordCount":27,"image":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif","articleSection":["PSV-Heidelberg"],"inLanguage":"ja"},{"@type":"WebPage","@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/","url":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/","name":"\u30af\u30ea\u30b9\u30de\u30b9 - Polizeisportverein Heidelberg e.V.","isPartOf":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#primaryimage"},"image":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif","datePublished":"2023-12-23T13:50:13+00:00","dateModified":"2023-12-23T13:50:26+00:00","author":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/#\/schema\/person\/606d929e0c904d931f9111388b7be25a"},"description":"PSV\u30cf\u30a4\u30c7\u30eb\u30d9\u30eb\u30b0\u3067\u306f\u3001\u4f1a\u54e1\u306e\u7686\u69d8\u3001\u3054\u5bb6\u65cf\u306e\u7686\u69d8\u3001\u305d\u3057\u3066\u5f53\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u3092\u3054\u89a7\u306e\u7686\u69d8\u306b\u3001\u30e1\u30ea\u30fc\u30af\u30ea\u30b9\u30de\u30b9\u3001\u5e73\u7a4f\u306a\u4f11\u65e5\u3001\u305d\u3057\u30662024\u5e74\u306e\u65b0\u5e74\u306e\u3054\u6328\u62f6\u3092\u7533\u3057\u4e0a\u3052\u307e\u3059\u3002","breadcrumb":{"@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#primaryimage","url":"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif","contentUrl":"https:\/\/polizeisportverein-heidelberg.de\/wp-content\/uploads\/2023\/12\/gif-christmas-tree-46-e1703338463885.gif","width":800,"height":533,"caption":"Weihnachten 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/polizeisportverein-heidelberg.de\/2023\/12\/23\/weihnachten-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/polizeisportverein-heidelberg.de\/"},{"@type":"ListItem","position":2,"name":"Weihnachten"}]},{"@type":"WebSite","@id":"https:\/\/polizeisportverein-heidelberg.de\/#website","url":"https:\/\/polizeisportverein-heidelberg.de\/","name":"\u30cf\u30a4\u30c7\u30eb\u30d9\u30eb\u30af\u8b66\u5bdf\u30b9\u30dd\u30fc\u30c4\u30af\u30e9\u30d6","description":"\u5e74\u9f62\u3092\u554f\u308f\u305a\u697d\u3057\u3081\u308b\u6b66\u9053\u3068\u7403\u6280","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polizeisportverein-heidelberg.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/polizeisportverein-heidelberg.de\/#\/schema\/person\/606d929e0c904d931f9111388b7be25a","name":"\u7de8\u96c6\u90e8","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/secure.gravatar.com\/avatar\/b1c6f2be27b1dead8bc2e492a47d416dcabd8dc824f2ee0bb102949c0ccfef98?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1c6f2be27b1dead8bc2e492a47d416dcabd8dc824f2ee0bb102949c0ccfef98?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1c6f2be27b1dead8bc2e492a47d416dcabd8dc824f2ee0bb102949c0ccfef98?s=96&d=mm&r=g","caption":"Redaktion"},"sameAs":["https:\/\/psv-hd.de"],"url":"https:\/\/polizeisportverein-heidelberg.de\/ja\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/posts\/6331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/comments?post=6331"}],"version-history":[{"count":0,"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/posts\/6331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/media\/6316"}],"wp:attachment":[{"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/media?parent=6331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/categories?post=6331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/polizeisportverein-heidelberg.de\/ja\/wp-json\/wp\/v2\/tags?post=6331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}